{"id":4972,"date":"2025-06-30T21:05:00","date_gmt":"2025-06-30T21:05:00","guid":{"rendered":"https:\/\/hepatology.ca\/?p=4972"},"modified":"2026-01-21T21:07:06","modified_gmt":"2026-01-21T21:07:06","slug":"4942-4","status":"publish","type":"post","link":"https:\/\/hepatology.ca\/fr\/2025\/06\/30\/4942-4\/","title":{"rendered":"Bulletin d&#039;information des membres de la CASL : JUIN 2025"},"content":{"rendered":"\n<style type=\"text\/css\">#outlook a { padding:0; }\n      body { margin:0;padding:0;-webkit-text-size-adjust:100%;-ms-text-size-adjust:100%; }\n      table, td { border-collapse:collapse;mso-table-lspace:0pt;mso-table-rspace:0pt; border:0px !important; }\n      img { border:0;height:auto;line-height:100%; outline:none;text-decoration:none;-ms-interpolation-mode:bicubic; }\n      p { display:block;margin:13px 0; }<\/style><!--[if mso]>\n    <noscript>\n    <xml>\n    <o:OfficeDocumentSettings>\n      <o:AllowPNG\/>\n      <o:PixelsPerInch>96<\/o:PixelsPerInch>\n    <\/o:OfficeDocumentSettings>\n    <\/xml>\n    <\/noscript>\n    <![endif]--><!--[if lte mso 11]>\n    <style type=\"text\/css\">\n      .mj-outlook-group-fix { width:100% !important; }\n    <\/style>\n    <![endif]--><!--[if !mso]><!--><link href=\"https:\/\/fonts.googleapis.com\/css2?family=Roboto:wght@300;400;500;700;800;900\" rel=\"stylesheet\" type=\"text\/css\"\/><style type=\"text\/css\">@import url(https:\/\/fonts.googleapis.com\/css2?family=Roboto:wght@300;400;500;700;800;900);<\/style><!--<![endif]--><style type=\"text\/css\">@media only screen and (min-width:480px) {\n        .mj-column-per-33 { width:33% !important; max-width: 33%; }\n.mj-column-per-67 { width:67% !important; max-width: 67%; }\n.mj-column-per-100 { width:100% !important; max-width: 100%; }\n.mj-column-per-66 { width:66% !important; max-width: 66%; }\n      }<\/style><style media=\"screen and (min-width:480px)\">.moz-text-html .mj-column-per-33 { width:33% !important; max-width: 33%; }\n.moz-text-html .mj-column-per-67 { width:67% !important; max-width: 67%; }\n.moz-text-html .mj-column-per-100 { width:100% !important; max-width: 100%; }\n.moz-text-html .mj-column-per-66 { width:66% !important; max-width: 66%; }<\/style><style type=\"text\/css\">[owa] .mj-column-per-33 { width:33% !important; max-width: 33%; }\n[owa] .mj-column-per-67 { width:67% !important; max-width: 67%; }\n[owa] .mj-column-per-100 { width:100% !important; max-width: 100%; }\n[owa] .mj-column-per-66 { width:66% !important; max-width: 66%; }<\/style><style type=\"text\/css\">@media only screen and (max-width:479px) {\n      table.mj-full-width-mobile { width: 100% !important; }\n      td.mj-full-width-mobile { width: auto !important; }\n    }<\/style><style type=\"text\/css\"><\/style><\/head><body style=\"word-spacing:normal;background-color:#ffffff;\"><div style=\"display:none;font-size:1px;color:#ffffff;line-height:1px;max-height:0px;max-width:0px;opacity:0;overflow:hidden;\">CASL Exclusives, Member Highlights, Events<\/div><div style=\"background-color:#ffffff;\" role=\"main\" lang=\"en\" dir=\"ltr\"><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:20px 0;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:198px;\" ><![endif]--><div class=\"mj-column-per-33 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"center\" style=\"font-size:0px;padding:10px 0px 10px 0px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:198px;\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/906abc5b-c030-4e57-8f54-65533e1e2047\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"198\" height=\"auto\"\/><\/td><\/tr><\/tbody><\/table><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><td class=\"\" style=\"vertical-align:top;width:402px;\" ><![endif]--><div class=\"mj-column-per-67 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"text-align: right; margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><a class=\"link-build-content\" style=\"color:inherit;text-decoration:none;; text-decoration: none;\" target=\"_blank\" href=\"[[PERMALINK]]\"><span style=\"color:#535353;font-family:Arial, sans-serif;\"><\/span><\/a><\/p><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h3 class=\"text-build-content\" style=\"text-align:right;; margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:2px;\"><b>JUNE 2025<\/b><\/span><\/h3><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><v:rect style=\"width:600px;\" xmlns:v=\"urn:schemas-microsoft-com:vml\" fill=\"true\" stroke=\"false\"><v:fill origin=\"0.5, 0\" position=\"0.5, 0\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content\" type=\"tile\" \/><v:textbox style=\"mso-fit-shape-to-text:true\" inset=\"0,0,0,0\"><![endif]--><div style=\"background:url(&#39;https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content&#39;) center top \/ auto no-repeat;background-position:center top;background-repeat:no-repeat;background-size:auto;margin:0px auto;max-width:600px;\"><div style=\"line-height:0;font-size:0;\"><table align=\"center\" background=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"background:url(&#39;https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content&#39;) center top \/ auto no-repeat;background-position:center top;background-repeat:no-repeat;background-size:auto;width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:15px 0px 15px 0px;padding-bottom:15px;padding-left:0px;padding-right:0px;padding-top:15px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h1 class=\"text-build-content\" style=\"line-height:47px;text-align:center;; margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#ffffff;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:30px;letter-spacing:2px;\"><b>MEMBERS NEWSLETTER<\/b><\/span><\/h1><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><\/div><!--[if mso | IE]><\/v:textbox><\/v:rect><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:0px 0px 0px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:16px;letter-spacing:1px;\"><b>IN THIS EDITION OF THE CASL MEMBERS NEWSLETTER:<\/b><\/span><\/h2><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:0px 0px 20px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#e99b23;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:16px;letter-spacing:1px;\"><b>CASL EXCLUSIVES<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:16px;letter-spacing:1px;\"><b>CASL HEPATIC HIGHLIGHTS &amp; MEMBER INSIGHTS<\/b><\/span><span style=\"color:#b8331f;font-family:Roboto, Helvetica, Arial, sans-serif;font-size:19px;letter-spacing:1px;\"><b><\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#8c4659;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:16px;letter-spacing:1px;\"><b>CASL EVENTS &amp; OTHER HEPATOLOGY EVENTS<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #000000;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #000000;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><v:rect style=\"width:600px;\" xmlns:v=\"urn:schemas-microsoft-com:vml\" fill=\"true\" stroke=\"false\"><v:fill origin=\"0.5, 0\" position=\"0.5, 0\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content\" type=\"tile\" \/><v:textbox style=\"mso-fit-shape-to-text:true\" inset=\"0,0,0,0\"><![endif]--><div style=\"background:url(&#39;https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content&#39;) center top \/ auto no-repeat;background-position:center top;background-repeat:no-repeat;background-size:auto;margin:0px auto;max-width:600px;\"><div style=\"line-height:0;font-size:0;\"><table align=\"center\" background=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"background:url(&#39;https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content&#39;) center top \/ auto no-repeat;background-position:center top;background-repeat:no-repeat;background-size:auto;width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:15px 0px 15px 0px;padding-bottom:15px;padding-left:0px;padding-right:0px;padding-top:15px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h1 class=\"text-build-content\" style=\"line-height:47px;text-align:center;; margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#ffffff;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:30px;letter-spacing:2px;\"><b>CASL EXCLUSIVES<\/b><\/span><\/h1><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><\/div><!--[if mso | IE]><\/v:textbox><\/v:rect><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:0px 0px 20px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#e99b23;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>CASL ANNUAL GENERAL MEETING<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 23px; margin: 10px 0; margin-top: 10px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\">The CASL Annual General Meeting was held virtually on ZOOM on Tuesday, June 10, 2025. <b>You can watch the recording on HepatoSite: CASL&#39;s Online Learning Portal! <\/b><\/span><\/p><p class=\"text-build-content\" style=\"line-height: 23px; margin: 10px 0;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\"><i>To ensure you don&#39;t miss out, you will receive a confirmation email whenever new content is added. Please keep an eye on your inbox for these notifications and follow the instructions provided to access the latest videos and resources.<\/i><\/span><\/p><p class=\"text-build-content\" style=\"line-height: 23px; margin: 10px 0; margin-bottom: 10px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\">Thank you for being a valued member of our community!<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:550px;\"><a href=\"https:\/\/hepatology.myabsorb.ca\/#\/online-courses\/b9df3eb0-1633-4a97-8c85-2e3d22ea6bde\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/abc4609b-dfdd-4822-959f-8c88952abeb4\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"550\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"#ffffff\" role=\"presentation\" style=\"border:2px solid #e99b23;border-radius:0px;cursor:auto;mso-padding-alt:10px 25px;background:#ffffff;\" valign=\"middle\"><a href=\"https:\/\/hepatology.myabsorb.ca\/#\/online-courses\/b9df3eb0-1633-4a97-8c85-2e3d22ea6bde\" style=\"display:inline-block;background:#ffffff;color:#ffffff;font-family:Verdana, Helvetica, Arial, sans-serif;font-size:14px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#e99b23;font-family:Arial, sans-serif;font-size:14px;\"><b>WATCH THE RECORDING<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:0px 0px 0px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:middle;width:402px;\" ><![endif]--><div class=\"mj-column-per-67 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:middle;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:middle;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#e99b23;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>The Canadian Liver Foundation (CLF) and the Canadian Association for Study of the Liver (CASL) historical archival credits. &#8211; The Impact of CLF and CASL on one Canadian Scientist, W. Wayne Lautt.<\/b><\/span><\/h2><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><td class=\"\" style=\"vertical-align:middle;width:198px;\" ><![endif]--><div class=\"mj-column-per-33 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:middle;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:middle;\" width=\"100%\"><tbody><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px 0px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:148px;\"><a href=\"https:\/\/hepatology.myabsorb.ca\/#\/online-courses\/b9df3eb0-1633-4a97-8c85-2e3d22ea6bde\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/scimar.ca\/wp-content\/uploads\/2022\/11\/Dr.-Wayne-Lautt.png\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"148\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><span style=\"color:#55575d;font-family:Arial, sans-serif;font-size:11px;\">W. Wayne Lautt<\/span><\/p><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:0px 0px 20px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 23px; margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\">The Canadian Association for the Study of the Liver (CASL) is proud to  to honor the contributions of pioneering researchers and clinicians, while also inspiring future generations in the field of liver health. This comprehensive update provides invaluable insights into the history and evolution of hepatology in Canada. By preserving and sharing these historical records, CASL aims to share the rich legacy and milestones that have shaped hepatology practice and research in Canada.<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"#ffffff\" role=\"presentation\" style=\"border:2px solid #e99b23;border-radius:0px;cursor:auto;mso-padding-alt:10px 25px;background:#ffffff;\" valign=\"middle\"><a href=\"https:\/\/hepatology.ca\/historical-update-to-casl-archives\/\" style=\"display:inline-block;background:#ffffff;color:#ffffff;font-family:Verdana, Helvetica, Arial, sans-serif;font-size:14px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#e99b23;font-family:Arial, sans-serif;font-size:14px;\"><b>READ THE ARTICLE<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#e99b23;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>2026-2027 CASL Clinical Fellowship Competition<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 23px; margin: 10px 0; margin-top: 10px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\"><b>The 2026-2027 CASL Clinical Fellowship Competition is now OPEN.<\/b><\/span><\/p><p class=\"text-build-content\" style=\"line-height: 23px; margin: 10px 0;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\">Fellowships are intended for candidates pursuing additional training in advanced clinical hepatology.  Applicants who have completed Internal Medicine, Pediatrics and\/or Gastroenterology training, and who intend to devote their future clinical practice to the management of adult or pediatric patients with liver diseases in Canada are prioritized. The fellowship placement will begin in the year following the application.<\/span><\/p><p class=\"text-build-content\" style=\"line-height: 23px; margin: 10px 0; margin-bottom: 10px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\">Deadline: Upload and submit your application along with all required documents by September 30, 2025.<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:550px;\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/hepatology.ca\/wp-content\/uploads\/2025\/06\/clinical-hep-fellowships-icons.jpg\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"550\" height=\"auto\"\/><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"#ffffff\" role=\"presentation\" style=\"border:2px solid #e99b23;border-radius:0px;cursor:auto;mso-padding-alt:10px 25px;background:#ffffff;\" valign=\"middle\"><a href=\"https:\/\/hepatology.ca\/education-events\/clinical-fellowships\/\" style=\"display:inline-block;background:#ffffff;color:#ffffff;font-family:Verdana, Helvetica, Arial, sans-serif;font-size:14px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#e99b23;font-family:Arial, sans-serif;font-size:14px;\"><b>SUBMIT YOUR APPLICATION<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #000000;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #000000;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:20px 0px 20px 0px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:600px;\"><a href=\"https:\/\/info.ocaliva.ca\/casl-may-2025\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/f7568314-5ae6-468d-869e-dca85eb771f5\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"600\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #000000;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #000000;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><v:rect style=\"width:600px;\" xmlns:v=\"urn:schemas-microsoft-com:vml\" fill=\"true\" stroke=\"false\"><v:fill origin=\"0.5, 0\" position=\"0.5, 0\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content\" type=\"tile\" \/><v:textbox style=\"mso-fit-shape-to-text:true\" inset=\"0,0,0,0\"><![endif]--><div style=\"background:url(&#39;https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content&#39;) center top \/ auto no-repeat;background-position:center top;background-repeat:no-repeat;background-size:auto;margin:0px auto;max-width:600px;\"><div style=\"line-height:0;font-size:0;\"><table align=\"center\" background=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"background:url(&#39;https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content&#39;) center top \/ auto no-repeat;background-position:center top;background-repeat:no-repeat;background-size:auto;width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:15px 0px 15px 0px;padding-bottom:15px;padding-left:0px;padding-right:0px;padding-top:15px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h1 class=\"text-build-content\" style=\"line-height:47px;text-align:center;; margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#ffffff;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:30px;letter-spacing:2px;\"><b>CASL HEPATIC HIGHLIGHTS &amp; MEMBER INSIGHTS<\/b><\/span><\/h1><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><\/div><!--[if mso | IE]><\/v:textbox><\/v:rect><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:10px 0px 20px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>The CASL- AMMI 2025 guidelines are available on the Canadian Liver Journal!<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 24px; margin: 10px 0; margin-top: 10px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\">The management of chronic hepatitis B: 2025 Guidelines update from the Canadian Association for the Study of the Liver and Association of Medical Microbiology and Infectious Disease Canada<\/span><\/p><p class=\"text-build-content\" style=\"line-height: 24px; margin: 10px 0; margin-bottom: 10px;\"><span style=\"color:#55575d;\">Authors: Clinical Practice Guidelines Committee Chair, Carla Osiowy, PhD, Panel Members, Fernando Alvarez, MD, Carla S Coffin, MD, Curtis L Cooper, MD, Scott K Fung, MD, Hin Hin Ko, S\u00e9bastien Poulin, MD, MSc, and Jennifer van Gennip, BSc<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:550px;\"><a href=\"https:\/\/utppublishing.com\/doi\/10.3138\/canlivj-2025-0012-e\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/2629954e-8fec-458e-ae1b-baec43b2eba2\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"550\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"transparent\" role=\"presentation\" style=\"border:2px solid #b8331f;border-radius:0px;cursor:auto;mso-padding-alt:10px 0px 10px 0px;background:transparent;\" valign=\"middle\"><a href=\"https:\/\/utppublishing.com\/doi\/10.3138\/canlivj-2025-0012-e\" style=\"display:inline-block;background:transparent;color:#ffffff;font-family:Arial, sans-serif;font-size:13px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 0px 10px 0px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#b8331f;font-size:13px;\"><b>READ THE GUIDELINES<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>Congratulations CASL members for receiving the Canadian Liver Journal Certificate of Merit<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 24px; margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\">The Certificate of Merit of the Canadian Liver Journal is awarded for significant contributions to the journal that exceed expectations.  The contributions can be in the form of willingness to review submitted papers for the journal, providing excellent reviews of submissions for the journal, submitting outstanding papers to the journal, promotion of the journal to colleagues and within the hepatology community, and for outstanding administrative work performed on behalf of the journal. The Certificate of Merit is not intended to be an annual award and there are no quotas for the number of recipients of the certificate.  This year, the Editor-in-Chief is proud to announce that the following have been recipients of the certificate:<\/span><\/p><ul><li style=\"line-height:24px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\"><i>Dr. Natasha Chandok, Western University<\/i><\/span><\/li><li style=\"line-height:24px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\"><i>Dr. Stephen Congly, University of Calgary<\/i><\/span><\/li><li style=\"line-height:24px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\"><i>Dr. Curtis Cooper, University of Ottawa<\/i><\/span><\/li><li style=\"line-height:24px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\"><i>Dr. Giada Sebastiani, McGill University<\/i><\/span><\/li><li style=\"line-height:24px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\"><i>Dr. Julie Zhu, Dalhousie University<\/i><\/span><\/li><\/ul><\/div><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>Integrating Clinical Excellence and Research: My Fellowship in Chronic Liver Disease and Transplantation \u2013 by Matthew Smith<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 24px; margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><span style=\"color:#55575d;font-family:Arial, Helvetica, sans-serif;font-size:14px;\">Embarking on a fellowship in chronic liver disease and transplantation has been a transformative journey for Matthew Smith, blending rigorous clinical practice with cutting-edge research. This experience has not only deepened his understanding of liver pathology but also highlighted the critical role of innovative treatments in improving patient outcomes. Through this fellowship, he has had the privilege of working alongside leading experts, contributing to groundbreaking studies, and witnessing firsthand the profound impact of our efforts on patients&#39; lives. This report encapsulates the lessons learned, challenges faced, and the invaluable knowledge gained during this pivotal chapter of his medical career.<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:0px 20px 0px 20px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:560px;\"><a href=\"https:\/\/hepatology.ca\/2025\/06\/06\/fellowship-hepatology-and-liver-transplantation\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/1be4506a-e48c-4d12-bd40-5e90a582940e\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"560\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"transparent\" role=\"presentation\" style=\"border:2px solid #b8331f;border-radius:0px;cursor:auto;mso-padding-alt:10px 0px 10px 0px;background:transparent;\" valign=\"middle\"><a href=\"https:\/\/hepatology.ca\/2025\/06\/06\/fellowship-hepatology-and-liver-transplantation\/\" style=\"display:inline-block;background:transparent;color:#ffffff;font-family:Arial, sans-serif;font-size:13px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 0px 10px 0px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#b8331f;font-size:13px;\"><b>READ THE REPORT<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>Congratulations to Dr. Mamatha Bhat (CASL Research Committee Co-Chair) for leading a $2M CIHR-funded project as Nominated Principal Applicant \u2014 and to Dr. Jennifer Flemming (Guidelines Committee Chair) as Principal Applicant and co-lead of Aim 1.<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 25px; margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:14px;\">Chronic liver disease impacts over three million Canadians, with over 5,000 Canadians succumbing annually to end-stage liver disease. Team Liver AI led by Dr. Mamatha Bhat, is dedicated to addressing these inequities through innovative artificial intelligence solutions. By harnessing the power of AI, they aim to create a robust framework that identifies and mitigates barriers to liver transplant access, ensuring equitable treatment for all patients. This initiative brings together a multidisciplinary team of experts committed to transforming the landscape of liver transplantation in Canada, ultimately striving for a future where every patient has the opportunity for a successful transplant and improved quality of life.<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:550px;\"><a href=\"https:\/\/hepatology.ca\/2025\/06\/02\/collaboratively-address-equity-challenges-in-liver-transplantation\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/hepatology.ca\/wp-content\/uploads\/2025\/06\/Collaboratively-address-equity-challenges-in-liver-Transplantation-1536x864.png\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"550\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"transparent\" role=\"presentation\" style=\"border:2px solid #b8331f;border-radius:0px;cursor:auto;mso-padding-alt:10px 25px;background:transparent;\" valign=\"middle\"><a href=\"https:\/\/hepatology.ca\/2025\/06\/02\/collaboratively-address-equity-challenges-in-liver-transplantation\/\" style=\"display:inline-block;background:transparent;color:#ffffff;font-family:Arial, sans-serif;font-size:13px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#b8331f;font-size:13px;\"><b>READ THE PROJECT<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>Addressing Liver Health Disparities: Dr. Felice Cinque\u2019s Advocacy and Research &#8211; Featuring our CASL LGBT+ trainee representative exciting work<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 25px; margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:14px;\">Dr. Felice Cinque has dedicated his career to addressing the pressing issue of liver health disparities. Through his pioneering research and unwavering advocacy, he has shed light on the systemic inequities that affect access to liver care and treatment outcomes. Dr. Cinque&#39;s work not only highlights the challenges faced by underserved populations but also proposes actionable solutions to bridge these gaps. This blog post delves into his journey, exploring the impactful initiatives he has spearheaded and the profound difference his efforts have made in the field of liver health. Read his blog post to understand the critical importance of equitable healthcare and the strides being made to ensure everyone has access to the care they need.<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"transparent\" role=\"presentation\" style=\"border:2px solid #b8331f;border-radius:0px;cursor:auto;mso-padding-alt:10px 25px;background:transparent;\" valign=\"middle\"><a href=\"https:\/\/hepatology.ca\/2025\/06\/06\/addressing-liver-health-disparities-felice-cinque\/\" style=\"display:inline-block;background:transparent;color:#ffffff;font-family:Arial, sans-serif;font-size:13px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#b8331f;font-size:13px;\"><b>READ THE BLOG POST<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>Congratulations Yashasavi Sachar for being selected as a 2025 AASLD Foundation Emerging Liver Scholar.<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 25px; margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:14px;\">The Emerging Liver Scholar Award is designed to promote the study of hepatology among outstanding residents who have the potential for a career in academic medicine and who may be interested in choosing adult or pediatric gastroenterology, hepatology, hepatopathology, surgery or GI radiology with an emphasis on hepatobiliary imaging as their career focus.<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:550px;\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/6286f646-6558-478e-8afa-867faa878cb2\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"550\" height=\"auto\"\/><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>WHAT ADVICE WOULD YOU GIVE AS A LIVER EXPERT?<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"line-height: 25px; margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:14px;\">Help us bring awareness of liver health to Canada. Tell us one piece of advice you would give to the general public as a liver expert. Click below to answer.<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"transparent\" role=\"presentation\" style=\"border:2px solid #b8331f;border-radius:0px;cursor:auto;mso-padding-alt:10px 25px;background:transparent;\" valign=\"middle\"><a href=\"https:\/\/forms.office.com\/pages\/responsepage.aspx?id=QU4UrAGA8EieHBcHFu0GtrFUGQuUSbtHrMip-UoiGRBUOFI0VzdLRFRWODBNRDBON1pUMEE1MVpIRC4u&amp;route=shorturl\" style=\"display:inline-block;background:transparent;color:#ffffff;font-family:Arial, sans-serif;font-size:13px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#b8331f;font-size:13px;\"><b>ANSWER HERE<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #E6E6E6;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#b8331f;font-family:Arial, Helvetica, sans-serif;font-size:20px;\"><i><b>Started a new job, got promoted, published research, or recognized for other outstanding contributions? Submit your or a fellow CASL member&#39;s achievements to CASL via email at <\/b><\/i><\/span><a class=\"link-build-content\" style=\"color:inherit;text-decoration:none;; text-decoration: none;\" href=\"mailto:casl@hepatology.ca\"><span style=\"color:#b8331f;font-family:Arial, Helvetica, sans-serif;font-size:20px;\"><i><b>casl@hepatology.ca<\/b><\/i><\/span><\/a><span style=\"color:#b8331f;font-family:Arial, Helvetica, sans-serif;font-size:20px;\"><i><b>!<\/b><\/i><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 2px #000000;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 2px #000000;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><v:rect style=\"width:600px;\" xmlns:v=\"urn:schemas-microsoft-com:vml\" fill=\"true\" stroke=\"false\"><v:fill origin=\"0.5, 0\" position=\"0.5, 0\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content\" type=\"tile\" \/><v:textbox style=\"mso-fit-shape-to-text:true\" inset=\"0,0,0,0\"><![endif]--><div style=\"background:url(&#39;https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content&#39;) center top \/ auto no-repeat;background-position:center top;background-repeat:no-repeat;background-size:auto;margin:0px auto;max-width:600px;\"><div style=\"line-height:0;font-size:0;\"><table align=\"center\" background=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"background:url(&#39;https:\/\/05hit.mjt.lu\/img2\/05hit\/8e2938ad-331c-4669-bf98-f4274402686e\/content&#39;) center top \/ auto no-repeat;background-position:center top;background-repeat:no-repeat;background-size:auto;width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:15px 0px 15px 0px;padding-bottom:15px;padding-left:0px;padding-right:0px;padding-top:15px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h1 class=\"text-build-content\" style=\"line-height:47px;text-align:center;; margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#ffffff;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:30px;letter-spacing:2px;\"><b>CASL EVENTS &amp; OTHER HEPATOLOGY EVENTS<\/b><\/span><\/h1><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><\/div><!--[if mso | IE]><\/v:textbox><\/v:rect><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:20px 0;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td style=\"font-size:0px;word-break:break-word;\"><div style=\"height:10px;line-height:10px;\">\u200a<\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"border:2px solid #8c4659;direction:ltr;font-size:0px;padding:20px 0;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:596px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:546px;\"><a href=\"https:\/\/www.caslstc.ca\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/894929ee-e5f4-4c48-a61f-972c3c1f788f\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"546\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#8c4659;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>The\u202f2025 CASL Single Topic Conference on Autoimmune and Rare Liver Disease (CASL STC) is taking place from\u202fOctober 6-7, 2025, at\u202fThe Westin Bayshore, Vancouver.<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"transparent\" role=\"presentation\" style=\"border:2px solid #8c4659;border-radius:0px;cursor:auto;mso-padding-alt:10px 25px;background:transparent;\" valign=\"middle\"><a href=\"https:\/\/www.caslstc.ca\/\" style=\"display:inline-block;background:transparent;color:#ffffff;font-family:Arial, sans-serif;font-size:13px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#8c4659;font-size:13px;\"><b>LEARN MORE<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:20px 0;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td style=\"font-size:0px;word-break:break-word;\"><div style=\"height:10px;line-height:10px;\">\u200a<\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"border:2px solid #8c4659;direction:ltr;font-size:0px;padding:0px 0px 0px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:393.36px;\" ><![endif]--><div class=\"mj-column-per-66 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:20px 20px 20px 20px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\" class=\"mj-full-width-mobile\"><tbody><tr><td style=\"width:353px;\" class=\"mj-full-width-mobile\"><a href=\"https:\/\/www.islscongress.com\/isls2025\/registration\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/4b28982e-be13-43e7-9284-8f9cae2b1c63\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"353\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><td class=\"\" style=\"vertical-align:top;width:196.68px;\" ><![endif]--><div class=\"mj-column-per-33 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#8c4659;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>The 6th Congress of International Advanced HBP Surgery (ISLS 2025)<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"margin: 10px 0; margin-top: 10px;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:13px;\"><b>OCTOBER 22 &#8211; 25, 2025<\/b><\/span><\/p><p class=\"text-build-content\" style=\"margin: 10px 0;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:13px;\"><b>SHERATON CENTRE TORONTO HOTEL<\/b><\/span><\/p><p class=\"text-build-content\" style=\"margin: 10px 0; margin-bottom: 10px;\"><a class=\"link-build-content\" style=\"color:inherit;text-decoration:none;; text-decoration: none;\" target=\"_blank\" href=\"https:\/\/www.islscongress.com\/\"><span style=\"color:#535353;\"><u>www.islscongress.com<\/u><\/span><\/a><\/p><\/div><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"#8c4659\" role=\"presentation\" style=\"border:none;border-radius:3px;cursor:auto;mso-padding-alt:10px 25px;background:#8c4659;\" valign=\"middle\"><a href=\"https:\/\/www.islscongress.com\/isls2025\/registration\" style=\"display:inline-block;background:#8c4659;color:#ffffff;font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:3px;\" target=\"_blank\"><span style=\"color:#ffffff;font-family:Arial, sans-serif;font-size:13px;\">Register Now<\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"text-align: center; margin: 10px 0; margin-top: 10px; margin-bottom: 10px;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:13px;\"><b>Deadline: Aug 10, 2025<\/b><\/span><\/p><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:20px 0;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td style=\"font-size:0px;word-break:break-word;\"><div style=\"height:10px;line-height:10px;\">\u200a<\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"border:2px solid #8c4659;direction:ltr;font-size:0px;padding:0px 0px 0px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:393.36px;\" ><![endif]--><div class=\"mj-column-per-66 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:20px 20px 20px 20px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\" class=\"mj-full-width-mobile\"><tbody><tr><td style=\"width:353px;\" class=\"mj-full-width-mobile\"><a href=\"https:\/\/www.deiintransplant.com\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/32a9efcf-8a87-4340-a4f7-1ed3fe21da30\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"353\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><td class=\"\" style=\"vertical-align:top;width:196.68px;\" ><![endif]--><div class=\"mj-column-per-33 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#8c4659;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>Advancing Diversity, Equity &amp; Inclusion in Transplantation: A Global Perspective Conference<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"margin: 10px 0; margin-top: 10px;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:13px;\"><b>OCTOBER 25 &#8211; 26, 2025<\/b><\/span><\/p><p class=\"text-build-content\" style=\"margin: 10px 0;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:13px;\"><b>SHERATON CENTRE TORONTO HOTEL<\/b><\/span><\/p><p class=\"text-build-content\" style=\"margin: 10px 0; margin-bottom: 10px;\"><a class=\"link-build-content\" style=\"color:inherit;text-decoration:none;; text-decoration: none;\" target=\"_blank\" href=\"https:\/\/www.deiintransplant.com\/\"><span style=\"color:#535353;\"><u>deiintransplant.com<\/u><\/span><\/a><\/p><\/div><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"#8c4659\" role=\"presentation\" style=\"border:none;border-radius:3px;cursor:auto;mso-padding-alt:10px 25px;background:#8c4659;\" valign=\"middle\"><a href=\"https:\/\/www.deiintransplant.com\/\" style=\"display:inline-block;background:#8c4659;color:#ffffff;font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:3px;\" target=\"_blank\"><span style=\"color:#ffffff;font-family:Arial, sans-serif;font-size:13px;\">Register Now<\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:20px 0;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td style=\"font-size:0px;word-break:break-word;\"><div style=\"height:10px;line-height:10px;\">\u200a<\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"border:2px solid #8c4659;direction:ltr;font-size:0px;padding:20px 0;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:596px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\"><tbody><tr><td style=\"width:546px;\"><a href=\"https:\/\/forum.digestivehealthcentrebc.ca\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/b1559de2-8f75-42e2-b564-8c40116db2be\/content\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"546\" height=\"auto\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#8c4659;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>Save The Date for the Digestive Health Centre (DHC) Forum 2025, taking place from\u202fNovember 24\u201325, 2025, in\u202fVancouver, British Columbia.<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"center\" vertical-align=\"middle\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:separate;width:100%;line-height:100%;\"><tbody><tr><td align=\"center\" bgcolor=\"transparent\" role=\"presentation\" style=\"border:2px solid #8c4659;border-radius:0px;cursor:auto;mso-padding-alt:10px 25px;background:transparent;\" valign=\"middle\"><a href=\"https:\/\/forum.digestivehealthcentrebc.ca\/\" style=\"display:inline-block;background:transparent;color:#ffffff;font-family:Arial, sans-serif;font-size:13px;font-weight:normal;line-height:120%;margin:0;text-decoration:none;text-transform:none;padding:10px 25px;mso-padding-alt:0px;border-radius:0px;\" target=\"_blank\"><span style=\"color:#8c4659;font-size:13px;\"><b>LEARN MORE<\/b><\/span><\/a><\/td><\/tr><\/tbody><\/table><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:20px 0;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td style=\"font-size:0px;word-break:break-word;\"><div style=\"height:10px;line-height:10px;\">\u200a<\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"border:2px solid #8c4659;direction:ltr;font-size:0px;padding:0px 0px 0px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:393.36px;\" ><![endif]--><div class=\"mj-column-per-66 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:20px 20px 20px 20px;word-break:break-word;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"border-collapse:collapse;border-spacing:0px;\" class=\"mj-full-width-mobile\"><tbody><tr><td style=\"width:353px;\" class=\"mj-full-width-mobile\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/hepatology.ca\/wp-content\/uploads\/2025\/01\/HCV-Flavi_Save-the-date-V0-1536x1086.png\" style=\"border:none;display:block;outline:none;text-decoration:none;height:auto;width:100%;font-size:13px;\" width=\"353\" height=\"auto\"\/><\/td><\/tr><\/tbody><\/table><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><td class=\"\" style=\"vertical-align:top;width:196.68px;\" ><![endif]--><div class=\"mj-column-per-33 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><h2 class=\"text-build-content\" style=\"margin-top: 10px; margin-bottom: 10px; font-weight: normal;\"><span style=\"color:#8c4659;font-family:Arial Black, Helvetica, Arial, sans-serif;font-size:18px;letter-spacing:1px;\"><b>31st International Symposium HCV-Flavi 2025<\/b><\/span><\/h2><\/div><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:10px 25px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;letter-spacing:normal;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"margin: 10px 0; margin-top: 10px;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:13px;\"><b>OCTOBER 13 &#8211; 16, 2025<\/b><\/span><\/p><p class=\"text-build-content\" style=\"margin: 10px 0;\"><span style=\"color:#535353;font-family:Arial, sans-serif;font-size:13px;\"><b>DUKE-NUS MEDICAL SCHOOL, SINGAPORE<\/b><\/span><\/p><p class=\"text-build-content\" style=\"margin: 10px 0; margin-bottom: 10px;\"><span style=\"color:#535353;\">SAVE THE DATE!<\/span><\/p><\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:20px 0;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td style=\"font-size:0px;word-break:break-word;\"><div style=\"height:10px;line-height:10px;\">\u200a<\/div><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" class=\"\" role=\"presentation\" style=\"width:600px;\" width=\"600\" bgcolor=\"#b8331f\" ><tr><td style=\"line-height:0px;font-size:0px;mso-line-height-rule:exactly;\"><![endif]--><div style=\"background:#b8331f;background-color:#b8331f;margin:0px auto;max-width:600px;\"><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"background:#b8331f;background-color:#b8331f;width:100%;\"><tbody><tr><td style=\"direction:ltr;font-size:0px;padding:0px 0px 0px 0px;text-align:center;\"><!--[if mso | IE]><table role=\"presentation\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\"><tr><td class=\"\" style=\"vertical-align:top;width:600px;\" ><![endif]--><div class=\"mj-column-per-100 mj-outlook-group-fix\" style=\"font-size:0px;text-align:left;direction:ltr;display:inline-block;vertical-align:top;width:100%;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"vertical-align:top;\" width=\"100%\"><tbody><tr><td align=\"center\" style=\"font-size:0px;padding:10px 25px;word-break:break-word;\"><p style=\"border-top:solid 1px #8e8e8e;font-size:1px;margin:0px auto;width:100%;\"><\/p><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"border-top:solid 1px #8e8e8e;font-size:1px;margin:0px auto;width:550px;\" role=\"presentation\" width=\"550px\" ><tr><td style=\"height:0;line-height:0;\">  \n<\/td><\/tr><\/table><![endif]--><\/td><\/tr><tr><td align=\"left\" style=\"font-size:0px;padding:0px 20px 0px 20px;padding-top:0px;padding-bottom:0px;word-break:break-word;\"><div style=\"font-family:Verdana, Helvetica, Arial, sans-serif;font-size:13px;line-height:1;text-align:left;color:#000000;\"><p class=\"text-build-content\" style=\"text-align: center; margin: 10px 0; margin-top: 10px;\"><span style=\"color:#f6f4f4;font-family:Arial, sans-serif;font-size:12px;line-height:22px;\">This e-mail has been sent to @, <\/span><a class=\"link-build-content\" style=\"color:inherit;text-decoration:none;; text-decoration: none;\" target=\"_blank\" href=\"https:\/\/05hit.mjt.lu\/unsub2?m=&amp;b=&amp;e=d1afb4bd&amp;x=0J_BmcrKaaE8oQM0QanDTA&amp;hl=en\"><span style=\"color:#f6f4f4;font-family:Arial, sans-serif;font-size:12px;line-height:22px;\">click here to unsubscribe<\/span><\/a><span style=\"color:#f6f4f4;font-family:Arial, sans-serif;font-size:12px;line-height:22px;\">.<\/span><\/p><p class=\"text-build-content\" style=\"text-align: center; margin: 10px 0;\"><a class=\"link-build-content\" style=\"color:inherit;text-decoration:none;; text-decoration: none;\" target=\"_blank\" href=\"https:\/\/hepatology.ca\/\"><span style=\"color:#f6f4f4;font-family:Arial, sans-serif;font-size:12px;line-height:22px;\"><u>CASL &#8211; Canadian Association for the Study of the Liver<\/u><\/span><\/a><\/p><p class=\"text-build-content\" style=\"text-align: center; margin: 10px 0;\"><span style=\"color:#f6f4f4;font-family:Arial, sans-serif;font-size:12px;line-height:22px;\">The Canadian Association for the Study of the Liver (CASL) aims to eliminate liver disease through education, advocacy, and the ongoing research of our members. We are Canada&#39;s Liver Experts.<\/span><\/p><p class=\"text-build-content\" style=\"text-align: center; margin: 10px 0;\"><a class=\"link-build-content\" style=\"color:inherit;text-decoration:none;; text-decoration: none;\" target=\"_blank\" href=\"https:\/\/hepatology.ca\/\"><span style=\"color:#f6f4f4;font-family:Arial, sans-serif;font-size:12px;line-height:22px;\"><u>https:\/\/hepatology.ca\/<\/u><\/span><\/a><\/p><p class=\"text-build-content\" style=\"text-align: center; margin: 10px 0; margin-bottom: 10px;\"><span style=\"color:#f6f4f4;font-family:Arial, sans-serif;font-size:12px;line-height:22px;\">PO BOX 19020 Vancouver RPO 4th Ave, BC, V6K 4R8<\/span><\/p><\/div><\/td><\/tr><tr><td align=\"center\" style=\"background:#ffffff;font-size:0px;padding:10px 25px;word-break:break-word;\"><!--[if mso | IE]><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" ><tr><td><![endif]--><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"float:none;display:inline-table;\"><tbody><tr><td aria-hidden=\"true\" style=\"padding:4px;vertical-align:middle;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"background:#000000;border-radius:3px;width:20px;\"><tbody><tr><td style=\"padding:0px 0px 0px 0px;font-size:0;height:20px;vertical-align:middle;width:20px;\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=[[SHORT_PERMALINK]]\" target=\"_blank\"><img decoding=\"async\" alt=\"\" height=\"20\" src=\"https:\/\/www.mailjet.com\/images\/theme\/v1\/icons\/ico-social\/facebook.png\" style=\"border-radius:3px;display:block;\" width=\"20\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><td style=\"vertical-align:middle;padding:4px 4px 4px 0;\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=[[SHORT_PERMALINK]]\" style=\"color:#333333;font-size:13px;font-family:Ubuntu, Helvetica, Arial, sans-serif;line-height:22px;text-decoration:none;\" target=\"_blank\">Share<\/a><\/td><\/tr><\/tbody><\/table><!--[if mso | IE]><\/td><td><![endif]--><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"float:none;display:inline-table;\"><tbody><tr><td aria-hidden=\"true\" style=\"padding:4px;vertical-align:middle;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"background:#000000;border-radius:3px;width:20px;\"><tbody><tr><td style=\"padding:0px 0px 0px 0px;font-size:0;height:20px;vertical-align:middle;width:20px;\"><a href=\"https:\/\/twitter.com\/intent\/tweet?url=[[SHORT_PERMALINK]]\" target=\"_blank\"><img decoding=\"async\" alt=\"\" height=\"20\" src=\"https:\/\/www.mailjet.com\/images\/theme\/v1\/icons\/ico-social\/twitter-x.png\" style=\"border-radius:3px;display:block;\" width=\"20\"\/><\/a><\/td><\/tr><\/tbody><\/table><\/td><td style=\"vertical-align:middle;padding:4px 4px 4px 0;\"><a href=\"https:\/\/twitter.com\/intent\/tweet?url=[[SHORT_PERMALINK]]\" style=\"color:#333333;font-size:13px;font-family:Ubuntu, Helvetica, Arial, sans-serif;line-height:22px;text-decoration:none;\" target=\"_blank\">Tweet<\/a><\/td><\/tr><\/tbody><\/table><!--[if mso | IE]><\/td><td><![endif]--><table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"float:none;display:inline-table;\"><tbody><tr><td aria-hidden=\"true\" style=\"padding:4px;vertical-align:middle;\"><table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" role=\"presentation\" style=\"background:#000000;border-radius:3px;width:20px;\"><tbody><tr><td style=\"padding:0px 0px 0px 0px;font-size:0;height:20px;vertical-align:middle;width:20px;\"><img decoding=\"async\" alt=\"\" height=\"20\" src=\"https:\/\/www.mailjet.com\/images\/theme\/v1\/icons\/ico-social\/linkedin.png\" style=\"border-radius:3px;display:block;\" width=\"20\"\/><\/td><\/tr><\/tbody><\/table><\/td><td style=\"vertical-align:middle;padding:4px 4px 4px 0;\"><span style=\"color:#333333;font-size:13px;font-family:Ubuntu, Helvetica, Arial, sans-serif;line-height:22px;text-decoration:none;\">\u2800<\/span><\/td><\/tr><\/tbody><\/table><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/td><\/tr><\/tbody><\/table><\/div><!--[if mso | IE]><\/td><\/tr><\/table><![endif]--><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASL Exclusives, Member Highlights, Events JUNE 2025 MEMBERS NEWSLETTER IN THIS EDITION OF THE CASL MEMBERS NEWSLETTER: CASL EXCLUSIVES CASL [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0,"footnotes":""},"categories":[39],"tags":[],"class_list":["post-4972","post","type-post","status-publish","format-standard","hentry","category-newsletter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CASL Member Newsletter: JUNE 2025 - CASL - Canadian Association for the Study of the Liver<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hepatology.ca\/fr\/2025\/06\/30\/4942-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CASL Member Newsletter: JUNE 2025 - CASL - Canadian Association for the Study of the Liver\" \/>\n<meta property=\"og:description\" content=\"CASL Exclusives, Member Highlights, Events JUNE 2025 MEMBERS NEWSLETTER IN THIS EDITION OF THE CASL MEMBERS NEWSLETTER: CASL EXCLUSIVES CASL [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hepatology.ca\/fr\/2025\/06\/30\/4942-4\/\" \/>\n<meta property=\"og:site_name\" content=\"CASL - Canadian Association for the Study of the Liver\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-30T21:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T21:07:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/05hit.mjt.lu\/img2\/05hit\/906abc5b-c030-4e57-8f54-65533e1e2047\/content\" \/>\n<meta name=\"author\" content=\"CASL Secretariat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CASL Secretariat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/\"},\"author\":{\"name\":\"CASL Secretariat\",\"@id\":\"https:\\\/\\\/hepatology.ca\\\/#\\\/schema\\\/person\\\/39d256e18d0156b51395def7a49bf1c9\"},\"headline\":\"CASL Member Newsletter: JUNE 2025\",\"datePublished\":\"2025-06-30T21:05:00+00:00\",\"dateModified\":\"2026-01-21T21:07:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/\"},\"wordCount\":1267,\"publisher\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/05hit.mjt.lu\\\/img2\\\/05hit\\\/906abc5b-c030-4e57-8f54-65533e1e2047\\\/content\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/\",\"url\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/\",\"name\":\"CASL Member Newsletter: JUNE 2025 - CASL - Canadian Association for the Study of the Liver\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/05hit.mjt.lu\\\/img2\\\/05hit\\\/906abc5b-c030-4e57-8f54-65533e1e2047\\\/content\",\"datePublished\":\"2025-06-30T21:05:00+00:00\",\"dateModified\":\"2026-01-21T21:07:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/05hit.mjt.lu\\\/img2\\\/05hit\\\/906abc5b-c030-4e57-8f54-65533e1e2047\\\/content\",\"contentUrl\":\"https:\\\/\\\/05hit.mjt.lu\\\/img2\\\/05hit\\\/906abc5b-c030-4e57-8f54-65533e1e2047\\\/content\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hepatology.ca\\\/2025\\\/06\\\/30\\\/4942-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hepatology.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CASL Member Newsletter: JUNE 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hepatology.ca\\\/#website\",\"url\":\"https:\\\/\\\/hepatology.ca\\\/\",\"name\":\"CASL\",\"description\":\"Canada\u2019s home for liver experts\",\"publisher\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hepatology.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hepatology.ca\\\/#organization\",\"name\":\"Canadian Association for the Study of the Liver\",\"url\":\"https:\\\/\\\/hepatology.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/hepatology.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hepatology.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CASL-logo-transparent-background.png\",\"contentUrl\":\"https:\\\/\\\/hepatology.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CASL-logo-transparent-background.png\",\"width\":1040,\"height\":294,\"caption\":\"Canadian Association for the Study of the Liver\"},\"image\":{\"@id\":\"https:\\\/\\\/hepatology.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hepatology.ca\\\/#\\\/schema\\\/person\\\/39d256e18d0156b51395def7a49bf1c9\",\"name\":\"CASL Secretariat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa7f2b8758d740ff5cb43ebdaf188b8e274808e77fbdb667287f87af3d7d4f18?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa7f2b8758d740ff5cb43ebdaf188b8e274808e77fbdb667287f87af3d7d4f18?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa7f2b8758d740ff5cb43ebdaf188b8e274808e77fbdb667287f87af3d7d4f18?s=96&d=mm&r=g\",\"caption\":\"CASL Secretariat\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bulletin des membres de l&#039;ACSL\u00a0: JUIN 2025 - ACSL - Association canadienne pour l&#039;\u00e9tude du foie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hepatology.ca\/fr\/2025\/06\/30\/4942-4\/","og_locale":"fr_CA","og_type":"article","og_title":"CASL Member Newsletter: JUNE 2025 - CASL - Canadian Association for the Study of the Liver","og_description":"CASL Exclusives, Member Highlights, Events JUNE 2025 MEMBERS NEWSLETTER IN THIS EDITION OF THE CASL MEMBERS NEWSLETTER: CASL EXCLUSIVES CASL [&hellip;]","og_url":"https:\/\/hepatology.ca\/fr\/2025\/06\/30\/4942-4\/","og_site_name":"CASL - Canadian Association for the Study of the Liver","article_published_time":"2025-06-30T21:05:00+00:00","article_modified_time":"2026-01-21T21:07:06+00:00","og_image":[{"url":"https:\/\/05hit.mjt.lu\/img2\/05hit\/906abc5b-c030-4e57-8f54-65533e1e2047\/content","type":"","width":"","height":""}],"author":"CASL Secretariat","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CASL Secretariat","Estimation du temps de lecture":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/#article","isPartOf":{"@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/"},"author":{"name":"CASL Secretariat","@id":"https:\/\/hepatology.ca\/#\/schema\/person\/39d256e18d0156b51395def7a49bf1c9"},"headline":"CASL Member Newsletter: JUNE 2025","datePublished":"2025-06-30T21:05:00+00:00","dateModified":"2026-01-21T21:07:06+00:00","mainEntityOfPage":{"@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/"},"wordCount":1267,"publisher":{"@id":"https:\/\/hepatology.ca\/#organization"},"image":{"@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/#primaryimage"},"thumbnailUrl":"https:\/\/05hit.mjt.lu\/img2\/05hit\/906abc5b-c030-4e57-8f54-65533e1e2047\/content","articleSection":["Newsletter"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/","url":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/","name":"Bulletin des membres de l&#039;ACSL\u00a0: JUIN 2025 - ACSL - Association canadienne pour l&#039;\u00e9tude du foie","isPartOf":{"@id":"https:\/\/hepatology.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/#primaryimage"},"image":{"@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/#primaryimage"},"thumbnailUrl":"https:\/\/05hit.mjt.lu\/img2\/05hit\/906abc5b-c030-4e57-8f54-65533e1e2047\/content","datePublished":"2025-06-30T21:05:00+00:00","dateModified":"2026-01-21T21:07:06+00:00","breadcrumb":{"@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/#primaryimage","url":"https:\/\/05hit.mjt.lu\/img2\/05hit\/906abc5b-c030-4e57-8f54-65533e1e2047\/content","contentUrl":"https:\/\/05hit.mjt.lu\/img2\/05hit\/906abc5b-c030-4e57-8f54-65533e1e2047\/content"},{"@type":"BreadcrumbList","@id":"https:\/\/hepatology.ca\/2025\/06\/30\/4942-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hepatology.ca\/"},{"@type":"ListItem","position":2,"name":"CASL Member Newsletter: JUNE 2025"}]},{"@type":"WebSite","@id":"https:\/\/hepatology.ca\/#website","url":"https:\/\/hepatology.ca\/","name":"LCAP","description":"Le foyer canadien des experts du foie","publisher":{"@id":"https:\/\/hepatology.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hepatology.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/hepatology.ca\/#organization","name":"Association canadienne pour l&#039;\u00e9tude du foie","url":"https:\/\/hepatology.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/hepatology.ca\/#\/schema\/logo\/image\/","url":"https:\/\/hepatology.ca\/wp-content\/uploads\/2024\/06\/CASL-logo-transparent-background.png","contentUrl":"https:\/\/hepatology.ca\/wp-content\/uploads\/2024\/06\/CASL-logo-transparent-background.png","width":1040,"height":294,"caption":"Canadian Association for the Study of the Liver"},"image":{"@id":"https:\/\/hepatology.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hepatology.ca\/#\/schema\/person\/39d256e18d0156b51395def7a49bf1c9","name":"Secr\u00e9tariat de la LCAP","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/fa7f2b8758d740ff5cb43ebdaf188b8e274808e77fbdb667287f87af3d7d4f18?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa7f2b8758d740ff5cb43ebdaf188b8e274808e77fbdb667287f87af3d7d4f18?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa7f2b8758d740ff5cb43ebdaf188b8e274808e77fbdb667287f87af3d7d4f18?s=96&d=mm&r=g","caption":"CASL Secretariat"}}]}},"_links":{"self":[{"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/posts\/4972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/comments?post=4972"}],"version-history":[{"count":1,"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/posts\/4972\/revisions"}],"predecessor-version":[{"id":4975,"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/posts\/4972\/revisions\/4975"}],"wp:attachment":[{"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/media?parent=4972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/categories?post=4972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hepatology.ca\/fr\/wp-json\/wp\/v2\/tags?post=4972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}